{"id":13222,"date":"2021-09-20T11:00:05","date_gmt":"2021-09-20T14:00:05","guid":{"rendered":"https:\/\/www.diocesesaoluis.org.br\/home\/?p=13222"},"modified":"2021-09-21T09:21:10","modified_gmt":"2021-09-21T12:21:10","slug":"paroquia-santa-cruz-celebrou-a-festa-dos-padroeiros","status":"publish","type":"post","link":"https:\/\/www.diocesesaoluis.org.br\/home\/2021\/09\/20\/paroquia-santa-cruz-celebrou-a-festa-dos-padroeiros\/","title":{"rendered":"Par\u00f3quia Santa Cruz celebrou a festa dos padroeiros"},"content":{"rendered":"\n<p>No domingo (19), a Par\u00f3quia Santa Cruz, em S\u00e3o Lu\u00eds de Montes Belos, celebrou o encerramento da 37\u00aa festa em honra a Santa Cruz e Nossa Senhora das Dores. A Santa Missa foi presidida por Dom Lindomar Rocha e concelebrada pelos padres da comunidade do noviciado passionista, padres Tarc\u00edlio (p\u00e1roco), Felipe (vig\u00e1rio paroquial), Jos\u00e9 Roberto (mestre de novi\u00e7os) e Alcides (vice-mestre de novi\u00e7os). O reitor do Semin\u00e1rio Menor, Pe. Eduardo, tamb\u00e9m concelebrou. Estiveram presentes os novi\u00e7os passionistas, seminaristas menores e centenas de paroquianos. <br><br>Neste ano, a Festa da Par\u00f3quia Santa Cruz teve um tom muito especial, pois, em comunh\u00e3o com toda a Congrega\u00e7\u00e3o Passionista, foram celebrados os 300 anos de funda\u00e7\u00e3o. Por esta raz\u00e3o, a festa teve um olhar voltado para a espiritualidade passionista, para o carisma da paix\u00e3o. Dessa forma, em todos os dias das novenas, foi meditado um of\u00edcio votivo da paix\u00e3o e dos sofrimentos de Jesus, junto com Maria aos p\u00e9s da Cruz.  Assim, o tema da festa foi: &#8220;juntos com Maria aos p\u00e9s da Cruz, celebrando os 300 anos dos Passionistas, somos convidados a testemunhar a Paix\u00e3o de Jesus.&#8221;<\/p>\n\n\n\n<p>Os festeiros deste ano foram os cursilhistas da Par\u00f3quia, os quais n\u00e3o mediram esfor\u00e7os para a realiza\u00e7\u00e3o da festa. Todas as comunidades, pastorais e movimentos tiveram uma participa\u00e7\u00e3o efetiva. Mesmo com todos os limites que a pandemia imp\u00f5e, a Par\u00f3quia celebrou com muita beleza e espiritualidade mais esta grandiosa festa. <\/p>\n\n\n\n<div class=\"wp-block-gmedia-album gmedia-shortcode\"><div class=\"gmedia_gallery amron_module is_bot\" id=\"GmediaGallery_8\" data-gmid=\"8\" data-module=\"amron\"><script type=\"text\/javascript\">\n\t(function() {\n\t\tthis['GmediaGallery_8'] = {\n\t\t\t'settings':{\"collectionThumbRecomendedWidth\":\"260\",\"collectionPreloaderColor\":\"333333\",\"linkTargetWindow\":\"_blank\",\"thumbSpacing\":\"10\",\"tagsFilter\":\"1\",\"tagCloudAll\":\"All\",\"tagCloudTextColor\":\"rgba(0, 0, 0, 1)\",\"tagCloudTextColorOver\":\"rgba(255,255, 255, 1)\",\"tagCloudBgColor\":\"rgba(211, 211, 211, 1)\",\"tagCloudBgColorOver\":\"rgba(11, 11, 11, 1)\",\"collectionThumbHoverColor\":\"rgba(0, 0, 0, .7)\",\"collectionThumbContentBGColor\":\"rgba(245,245,245,1)\",\"collectionThumbTitleShow\":\"1\",\"collectionThumbTitleColor\":\"rgba(0,0,0,1)\",\"collectionThumbFontSize\":\"18\",\"collectionThumbDescriptionShow\":\"1\",\"collectionThumbDescriptionColor\":\"rgba(0,0,0,1)\",\"collectionThumbDescriptionFontSize\":\"15\",\"collectionReadMoreButtonLabel\":\"Read More\",\"collectionReadMoreButtonLabelColor\":\"rgba(255, 255, 255, 1)\",\"collectionReadMoreButtonBGColor\":\"rgba(0, 0, 0, 1)\",\"collectionReadMoreButtonLabelColorHover\":\"rgba(0, 0, 0, 1)\",\"collectionReadMoreButtonBGColorHover\":\"rgba(235,235,235,1)\",\"modaBgColor\":\"rgba(0,0,0,0.9)\",\"modalInfoBoxBgColor\":\"rgba(255,255,255,1)\",\"modalInfoBoxTitleTextColor\":\"000000\",\"modalInfoBoxTextColor\":\"333333\",\"infoBarCountersEnable\":\"1\",\"infoBarDateInfoEnable\":\"1\",\"lightBoxEnable\":\"1\",\"sliderPreloaderColor\":\"ffffff\",\"sliderBgColor\":\"rgba(0,0,0,0.8)\",\"sliderHeaderFooterBgColor\":\"000000\",\"sliderNavigationColor\":\"rgba(0,0,0,1)\",\"sliderNavigationIconColor\":\"rgba(255,255,255,1)\",\"sliderNavigationColorOver\":\"rgba(255,255,255,1)\",\"sliderNavigationIconColorOver\":\"rgba(0,0,0,1)\",\"sliderItemTitleFontSize\":\"24\",\"sliderItemTitleTextColor\":\"ffffff\",\"sliderThumbBarEnable\":\"0\",\"sliderThumbBarHoverColor\":\"ffffff\",\"sliderThumbSubMenuBackgroundColor\":\"rgba(0,0,0,1)\",\"sliderThumbSubMenuBackgroundColorOver\":\"rgba(255,255,255,1)\",\"sliderThumbSubMenuIconColor\":\"rgba(255,255,255,1)\",\"sliderThumbSubMenuIconHoverColor\":\"rgba(0,0,0,1)\",\"sliderInfoEnable\":\"1\",\"sliderItemDownload\":\"1\",\"sliderItemDiscuss\":\"1\",\"sliderSocialShareEnabled\":\"1\",\"sliderLikesEnabled\":\"1\",\"customCSS\":\"\",\"module_url\":\"https:\\\/\\\/www.diocesesaoluis.org.br\\\/home\\\/wp-content\\\/plugins\\\/grand-media\\\/module\\\/amron\",\"license\":\"\",\"post_url\":\"https:\\\/\\\/www.diocesesaoluis.org.br\\\/home\\\/wp-json\\\/wp\\\/v2\\\/posts\\\/13222\"},\n\t\t\t'appQuery':{\"orderby\":\"ID\",\"order\":\"DESC\",\"album__in\":\"8\",\"status\":[\"publish\"],\"limit\":100},\n\t\t\t'appApi':\"https:\\\/\\\/www.diocesesaoluis.org.br\\\/home\\\/?gmedia-app=1&gmappversion=4&gmmodule=1\",\n\t\t\t'appInfo':{\"name\":\"Festa Santa Cruz\",\"description\":\"\"}};\n\t})();\n<\/script>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>No domingo (19), a Par\u00f3quia Santa Cruz, em S\u00e3o Lu\u00eds de Montes Belos, celebrou o encerramento da 37\u00aa festa em honra a Santa Cruz e Nossa Senhora das Dores. A Santa Missa foi presidida por Dom Lindomar Rocha e concelebrada pelos padres da comunidade do noviciado passionista, padres Tarc\u00edlio (p\u00e1roco), Felipe (vig\u00e1rio paroquial), Jos\u00e9 Roberto<span class=\"read-more arrow\"><a href=\"https:\/\/www.diocesesaoluis.org.br\/home\/2021\/09\/20\/paroquia-santa-cruz-celebrou-a-festa-dos-padroeiros\/\" title=\"Read More\">&rarr;<\/a><\/span><\/p>\n","protected":false},"author":2,"featured_media":13221,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","footnotes":""},"categories":[106,73],"tags":[250,310,265],"class_list":{"0":"post-13222","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-forania-sao-luis-gonzaga","8":"category-paroquias","9":"tag-festa-do-padroeiro","10":"tag-forania-sao-luis-gonzaga","11":"tag-paroquias"},"featured_image_src":"https:\/\/www.diocesesaoluis.org.br\/home\/wp-content\/uploads\/2021\/09\/IMG-20210921-WA0003.jpg","author_info":{"display_name":false,"author_link":"https:\/\/www.diocesesaoluis.org.br\/home\/author\/lucas\/"},"_links":{"self":[{"href":"https:\/\/www.diocesesaoluis.org.br\/home\/wp-json\/wp\/v2\/posts\/13222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diocesesaoluis.org.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diocesesaoluis.org.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diocesesaoluis.org.br\/home\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diocesesaoluis.org.br\/home\/wp-json\/wp\/v2\/comments?post=13222"}],"version-history":[{"count":2,"href":"https:\/\/www.diocesesaoluis.org.br\/home\/wp-json\/wp\/v2\/posts\/13222\/revisions"}],"predecessor-version":[{"id":13224,"href":"https:\/\/www.diocesesaoluis.org.br\/home\/wp-json\/wp\/v2\/posts\/13222\/revisions\/13224"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diocesesaoluis.org.br\/home\/wp-json\/wp\/v2\/media\/13221"}],"wp:attachment":[{"href":"https:\/\/www.diocesesaoluis.org.br\/home\/wp-json\/wp\/v2\/media?parent=13222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diocesesaoluis.org.br\/home\/wp-json\/wp\/v2\/categories?post=13222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diocesesaoluis.org.br\/home\/wp-json\/wp\/v2\/tags?post=13222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}